{"id":12672,"date":"2021-08-30T09:14:58","date_gmt":"2021-08-30T07:14:58","guid":{"rendered":"https:\/\/came-italy.com\/?p=12672"},"modified":"2024-05-26T19:44:41","modified_gmt":"2024-05-26T17:44:41","slug":"wir-freuen-uns-auf-ihren-besuch-auf-der-coiltech-italia-2021-in-pordenone","status":"publish","type":"post","link":"https:\/\/came-italy.com\/de\/wir-freuen-uns-auf-ihren-besuch-auf-der-coiltech-italia-2021-in-pordenone\/","title":{"rendered":"Wir freuen uns auf Ihren Besuch auf der Coiltech Italia 2021 in Pordenone"},"content":{"rendered":"<p>Wir sind auf der Coiltech Italia 2021 vertreten, die am Mittwoch und Donnerstag, 22. und 23. September 2021, stattfindet.<\/p>\n<p>Dies ist eine gute Gelegenheit, uns wieder pers\u00f6nlich zu treffen und die Neuigkeiten zu den Produkten und Dienstleistungen von Came aus erster Hand zu erfahren. <\/p>\n<p>Sie finden uns in <strong>Halle 5 Stand B20-B22<\/strong>.<\/p>\n<p><a href=\"https:\/\/www.quickfairs.net\/visitatori\/form_visitatori_step1.asp?idf=99&#038;id_zona=2&#038;id_menu=9&#038;om=n\" rel=\"noopener\" target=\"_blank\">Unter dem folgenden Link k\u00f6nnen Sie sich online registrieren und die Eintrittskarte herunterladen.<\/a><\/p>\n<p>Sie k\u00f6nnen einen Termin mit uns vereinbaren, indem Sie die Nummer <a href=\"tel:+39 04444 88282\" rel=\"noopener\" target=\"_blank\">+39 04444 88282<\/a> anrufen<br \/>\noder eine E-Mail senden an <a href=\"mailto:consulting@came-italy.com\" rel=\"noopener\" target=\"_blank\">consulting@came-italy.com<\/a><\/p>\n<p><strong>Adresse<\/strong><br \/>\nPordenone Fiere<br \/>\nViale Treviso, 1 \u2013 33170 Pordenone<br \/>\nEingang (Ingresso) Nord<\/p>\n<p><strong>\u00d6ffnungszeiten f\u00fcr Besucher<\/strong><br \/>\nMittwoch, 22. September 9:00 \u2013 18:00 Uhr<br \/>\nDonnerstag, 23. September 9:00 \u2013 17:00 Uhr<\/p>\n<p><iframe loading=\"lazy\" style=\"border: 0;\" src=\"https:\/\/www.google.com\/maps\/embed?pb=!1m18!1m12!1m3!1d3007.7544120088296!2d12.656044800753435!3d45.94927276414008!2m3!1f0!2f0!3f0!3m2!1i1024!2i768!4f13.1!3m3!1m2!1s0x477964911ce9be7b%3A0xf0433eb62e2af156!2sPordenone+Fiere!5e0!3m2!1sit!2sit!4v1442737058775\" width=\"600\" height=\"450\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\"><\/iframe><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wir sind auf der Coiltech Italia 2021 vertreten, die am Mittwoch und Donnerstag, 22. und 23. September 2021, stattfindet. Dies ist eine gute Gelegenheit, uns wieder pers\u00f6nlich zu treffen und die Neuigkeiten zu den Produkten und Dienstleistungen von Came aus erster Hand zu erfahren. Sie finden uns in Halle 5 Stand B20-B22. Unter dem folgenden [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":12680,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[145],"tags":[1396,1397,1395,1399,1391,1398,1394,1381,1364,1390],"class_list":["post-12672","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-unkategorisiert","tag-besuch-coiltech-2021","tag-came-ausstellung-2021","tag-came-coiltech-pordenone","tag-came-stand-pordenone","tag-came-technologiepraesentation","tag-coiltech-eventdetails","tag-coiltech-italia-2021","tag-coiltech-italien-highlights","tag-elektromotorenmesse","tag-industriemesse-came"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Wir freuen uns auf Ihren Besuch auf der Coiltech Italia 2021 in Pordenone - Came Spa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/came-italy.com\/de\/wir-freuen-uns-auf-ihren-besuch-auf-der-coiltech-italia-2021-in-pordenone\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Wir freuen uns auf Ihren Besuch auf der Coiltech Italia 2021 in Pordenone - Came Spa\" \/>\n<meta property=\"og:description\" content=\"Wir sind auf der Coiltech Italia 2021 vertreten, die am Mittwoch und Donnerstag, 22. und 23. September 2021, stattfindet. Dies ist eine gute Gelegenheit, uns wieder pers\u00f6nlich zu treffen und die Neuigkeiten zu den Produkten und Dienstleistungen von Came aus erster Hand zu erfahren. Sie finden uns in Halle 5 Stand B20-B22. Unter dem folgenden [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/came-italy.com\/de\/wir-freuen-uns-auf-ihren-besuch-auf-der-coiltech-italia-2021-in-pordenone\/\" \/>\n<meta property=\"og:site_name\" content=\"Came Spa\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-30T07:14:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-26T17:44:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/came-italy.com\/wp-content\/uploads\/2021\/08\/Coiltech-2021-eng.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"maja\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"maja\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/came-italy.com\\\/de\\\/wir-freuen-uns-auf-ihren-besuch-auf-der-coiltech-italia-2021-in-pordenone\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/came-italy.com\\\/de\\\/wir-freuen-uns-auf-ihren-besuch-auf-der-coiltech-italia-2021-in-pordenone\\\/\"},\"author\":{\"name\":\"maja\",\"@id\":\"https:\\\/\\\/came-italy.com\\\/de\\\/#\\\/schema\\\/person\\\/32fb20fb33d897ac95c1b2479b03bdb9\"},\"headline\":\"Wir freuen uns auf Ihren Besuch auf der Coiltech Italia 2021 in Pordenone\",\"datePublished\":\"2021-08-30T07:14:58+00:00\",\"dateModified\":\"2024-05-26T17:44:41+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/came-italy.com\\\/de\\\/wir-freuen-uns-auf-ihren-besuch-auf-der-coiltech-italia-2021-in-pordenone\\\/\"},\"wordCount\":115,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/came-italy.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/came-italy.com\\\/de\\\/wir-freuen-uns-auf-ihren-besuch-auf-der-coiltech-italia-2021-in-pordenone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/came-italy.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Coiltech-2021-eng.jpg\",\"keywords\":[\"Besuch Coiltech 2021\",\"Came Ausstellung 2021\",\"Came Coiltech Pordenone\",\"Came Stand Pordenone\",\"Came Technologiepr\u00e4sentation\",\"Coiltech Eventdetails\",\"Coiltech Italia 2021\",\"Coiltech Italien Highlights\",\"Elektromotorenmesse\",\"Industriemesse Came\"],\"articleSection\":[\"Unkategorisiert\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/came-italy.com\\\/de\\\/wir-freuen-uns-auf-ihren-besuch-auf-der-coiltech-italia-2021-in-pordenone\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/came-italy.com\\\/de\\\/wir-freuen-uns-auf-ihren-besuch-auf-der-coiltech-italia-2021-in-pordenone\\\/\",\"url\":\"https:\\\/\\\/came-italy.com\\\/de\\\/wir-freuen-uns-auf-ihren-besuch-auf-der-coiltech-italia-2021-in-pordenone\\\/\",\"name\":\"Wir freuen uns auf Ihren Besuch auf der Coiltech Italia 2021 in Pordenone - Came Spa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/came-italy.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/came-italy.com\\\/de\\\/wir-freuen-uns-auf-ihren-besuch-auf-der-coiltech-italia-2021-in-pordenone\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/came-italy.com\\\/de\\\/wir-freuen-uns-auf-ihren-besuch-auf-der-coiltech-italia-2021-in-pordenone\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/came-italy.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Coiltech-2021-eng.jpg\",\"datePublished\":\"2021-08-30T07:14:58+00:00\",\"dateModified\":\"2024-05-26T17:44:41+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/came-italy.com\\\/de\\\/wir-freuen-uns-auf-ihren-besuch-auf-der-coiltech-italia-2021-in-pordenone\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/came-italy.com\\\/de\\\/wir-freuen-uns-auf-ihren-besuch-auf-der-coiltech-italia-2021-in-pordenone\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/came-italy.com\\\/de\\\/wir-freuen-uns-auf-ihren-besuch-auf-der-coiltech-italia-2021-in-pordenone\\\/#primaryimage\",\"url\":\"https:\\\/\\\/came-italy.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Coiltech-2021-eng.jpg\",\"contentUrl\":\"https:\\\/\\\/came-italy.com\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/Coiltech-2021-eng.jpg\",\"width\":850,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/came-italy.com\\\/de\\\/wir-freuen-uns-auf-ihren-besuch-auf-der-coiltech-italia-2021-in-pordenone\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/came-italy.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Wir freuen uns auf Ihren Besuch auf der Coiltech Italia 2021 in Pordenone\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/came-italy.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/came-italy.com\\\/de\\\/\",\"name\":\"Came Spa\",\"description\":\"Avvolgimenti e componenti per motori elettrici\",\"publisher\":{\"@id\":\"https:\\\/\\\/came-italy.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/came-italy.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/came-italy.com\\\/de\\\/#organization\",\"name\":\"Came Spa\",\"url\":\"https:\\\/\\\/came-italy.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/came-italy.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/came-italy.com\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/logo-came-spa.png\",\"contentUrl\":\"https:\\\/\\\/came-italy.com\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/logo-came-spa.png\",\"width\":766,\"height\":129,\"caption\":\"Came Spa\"},\"image\":{\"@id\":\"https:\\\/\\\/came-italy.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/came-italy.com\\\/de\\\/#\\\/schema\\\/person\\\/32fb20fb33d897ac95c1b2479b03bdb9\",\"name\":\"maja\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/de9363bcafac780ede24c15396f5a17ff4d8e3076d874826acd6cdfa9a300222?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/de9363bcafac780ede24c15396f5a17ff4d8e3076d874826acd6cdfa9a300222?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/de9363bcafac780ede24c15396f5a17ff4d8e3076d874826acd6cdfa9a300222?s=96&d=mm&r=g\",\"caption\":\"maja\"},\"url\":\"https:\\\/\\\/came-italy.com\\\/de\\\/author\\\/maja\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Wir freuen uns auf Ihren Besuch auf der Coiltech Italia 2021 in Pordenone - Came Spa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/came-italy.com\/de\/wir-freuen-uns-auf-ihren-besuch-auf-der-coiltech-italia-2021-in-pordenone\/","og_locale":"de_DE","og_type":"article","og_title":"Wir freuen uns auf Ihren Besuch auf der Coiltech Italia 2021 in Pordenone - Came Spa","og_description":"Wir sind auf der Coiltech Italia 2021 vertreten, die am Mittwoch und Donnerstag, 22. und 23. September 2021, stattfindet. Dies ist eine gute Gelegenheit, uns wieder pers\u00f6nlich zu treffen und die Neuigkeiten zu den Produkten und Dienstleistungen von Came aus erster Hand zu erfahren. Sie finden uns in Halle 5 Stand B20-B22. Unter dem folgenden [&hellip;]","og_url":"https:\/\/came-italy.com\/de\/wir-freuen-uns-auf-ihren-besuch-auf-der-coiltech-italia-2021-in-pordenone\/","og_site_name":"Came Spa","article_published_time":"2021-08-30T07:14:58+00:00","article_modified_time":"2024-05-26T17:44:41+00:00","og_image":[{"width":850,"height":450,"url":"https:\/\/came-italy.com\/wp-content\/uploads\/2021\/08\/Coiltech-2021-eng.jpg","type":"image\/jpeg"}],"author":"maja","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"maja","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/came-italy.com\/de\/wir-freuen-uns-auf-ihren-besuch-auf-der-coiltech-italia-2021-in-pordenone\/#article","isPartOf":{"@id":"https:\/\/came-italy.com\/de\/wir-freuen-uns-auf-ihren-besuch-auf-der-coiltech-italia-2021-in-pordenone\/"},"author":{"name":"maja","@id":"https:\/\/came-italy.com\/de\/#\/schema\/person\/32fb20fb33d897ac95c1b2479b03bdb9"},"headline":"Wir freuen uns auf Ihren Besuch auf der Coiltech Italia 2021 in Pordenone","datePublished":"2021-08-30T07:14:58+00:00","dateModified":"2024-05-26T17:44:41+00:00","mainEntityOfPage":{"@id":"https:\/\/came-italy.com\/de\/wir-freuen-uns-auf-ihren-besuch-auf-der-coiltech-italia-2021-in-pordenone\/"},"wordCount":115,"commentCount":0,"publisher":{"@id":"https:\/\/came-italy.com\/de\/#organization"},"image":{"@id":"https:\/\/came-italy.com\/de\/wir-freuen-uns-auf-ihren-besuch-auf-der-coiltech-italia-2021-in-pordenone\/#primaryimage"},"thumbnailUrl":"https:\/\/came-italy.com\/wp-content\/uploads\/2021\/08\/Coiltech-2021-eng.jpg","keywords":["Besuch Coiltech 2021","Came Ausstellung 2021","Came Coiltech Pordenone","Came Stand Pordenone","Came Technologiepr\u00e4sentation","Coiltech Eventdetails","Coiltech Italia 2021","Coiltech Italien Highlights","Elektromotorenmesse","Industriemesse Came"],"articleSection":["Unkategorisiert"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/came-italy.com\/de\/wir-freuen-uns-auf-ihren-besuch-auf-der-coiltech-italia-2021-in-pordenone\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/came-italy.com\/de\/wir-freuen-uns-auf-ihren-besuch-auf-der-coiltech-italia-2021-in-pordenone\/","url":"https:\/\/came-italy.com\/de\/wir-freuen-uns-auf-ihren-besuch-auf-der-coiltech-italia-2021-in-pordenone\/","name":"Wir freuen uns auf Ihren Besuch auf der Coiltech Italia 2021 in Pordenone - Came Spa","isPartOf":{"@id":"https:\/\/came-italy.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/came-italy.com\/de\/wir-freuen-uns-auf-ihren-besuch-auf-der-coiltech-italia-2021-in-pordenone\/#primaryimage"},"image":{"@id":"https:\/\/came-italy.com\/de\/wir-freuen-uns-auf-ihren-besuch-auf-der-coiltech-italia-2021-in-pordenone\/#primaryimage"},"thumbnailUrl":"https:\/\/came-italy.com\/wp-content\/uploads\/2021\/08\/Coiltech-2021-eng.jpg","datePublished":"2021-08-30T07:14:58+00:00","dateModified":"2024-05-26T17:44:41+00:00","breadcrumb":{"@id":"https:\/\/came-italy.com\/de\/wir-freuen-uns-auf-ihren-besuch-auf-der-coiltech-italia-2021-in-pordenone\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/came-italy.com\/de\/wir-freuen-uns-auf-ihren-besuch-auf-der-coiltech-italia-2021-in-pordenone\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/came-italy.com\/de\/wir-freuen-uns-auf-ihren-besuch-auf-der-coiltech-italia-2021-in-pordenone\/#primaryimage","url":"https:\/\/came-italy.com\/wp-content\/uploads\/2021\/08\/Coiltech-2021-eng.jpg","contentUrl":"https:\/\/came-italy.com\/wp-content\/uploads\/2021\/08\/Coiltech-2021-eng.jpg","width":850,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/came-italy.com\/de\/wir-freuen-uns-auf-ihren-besuch-auf-der-coiltech-italia-2021-in-pordenone\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/came-italy.com\/de\/"},{"@type":"ListItem","position":2,"name":"Wir freuen uns auf Ihren Besuch auf der Coiltech Italia 2021 in Pordenone"}]},{"@type":"WebSite","@id":"https:\/\/came-italy.com\/de\/#website","url":"https:\/\/came-italy.com\/de\/","name":"Came Spa","description":"Avvolgimenti e componenti per motori elettrici","publisher":{"@id":"https:\/\/came-italy.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/came-italy.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/came-italy.com\/de\/#organization","name":"Came Spa","url":"https:\/\/came-italy.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/came-italy.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/came-italy.com\/wp-content\/uploads\/2016\/07\/logo-came-spa.png","contentUrl":"https:\/\/came-italy.com\/wp-content\/uploads\/2016\/07\/logo-came-spa.png","width":766,"height":129,"caption":"Came Spa"},"image":{"@id":"https:\/\/came-italy.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/came-italy.com\/de\/#\/schema\/person\/32fb20fb33d897ac95c1b2479b03bdb9","name":"maja","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/de9363bcafac780ede24c15396f5a17ff4d8e3076d874826acd6cdfa9a300222?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/de9363bcafac780ede24c15396f5a17ff4d8e3076d874826acd6cdfa9a300222?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/de9363bcafac780ede24c15396f5a17ff4d8e3076d874826acd6cdfa9a300222?s=96&d=mm&r=g","caption":"maja"},"url":"https:\/\/came-italy.com\/de\/author\/maja\/"}]}},"_links":{"self":[{"href":"https:\/\/came-italy.com\/de\/wp-json\/wp\/v2\/posts\/12672","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/came-italy.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/came-italy.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/came-italy.com\/de\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/came-italy.com\/de\/wp-json\/wp\/v2\/comments?post=12672"}],"version-history":[{"count":1,"href":"https:\/\/came-italy.com\/de\/wp-json\/wp\/v2\/posts\/12672\/revisions"}],"predecessor-version":[{"id":12673,"href":"https:\/\/came-italy.com\/de\/wp-json\/wp\/v2\/posts\/12672\/revisions\/12673"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/came-italy.com\/de\/wp-json\/wp\/v2\/media\/12680"}],"wp:attachment":[{"href":"https:\/\/came-italy.com\/de\/wp-json\/wp\/v2\/media?parent=12672"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/came-italy.com\/de\/wp-json\/wp\/v2\/categories?post=12672"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/came-italy.com\/de\/wp-json\/wp\/v2\/tags?post=12672"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}