{"id":15971,"date":"2023-10-05T11:38:16","date_gmt":"2023-10-05T09:38:16","guid":{"rendered":"https:\/\/came-italy.com\/?p=15971"},"modified":"2023-10-05T15:38:25","modified_gmt":"2023-10-05T13:38:25","slug":"vielen-dank-fuer-ihren-besuch-bei-uns-auf-der-coiltech-pordenone-2023","status":"publish","type":"post","link":"https:\/\/came-italy.com\/de\/vielen-dank-fuer-ihren-besuch-bei-uns-auf-der-coiltech-pordenone-2023\/","title":{"rendered":"Vielen Dank f\u00fcr Ihren Besuch bei uns auf der Coiltech Pordenone 2023"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" class=\"wp-post-image alignnone size-large wp-image-12131\" style=\"display: none;\" src=\"https:\/\/came-italy.com\/wp-content\/uploads\/2023\/10\/coiltech2023.png\" alt=\"\" width=\"850\" height=\"478\"><\/p>\n<div class=\"videoWrapper\"><iframe loading=\"lazy\" src=\"https:\/\/www.youtube.com\/embed\/yE8Hh5VfzhA?si=UgZ2o8GhbpcdCIvR\" width=\"850\" height=\"478\" frameborder=\"0\" allowfullscreen=\"allowfullscreen\" data-mce-fragment=\"1\"><\/iframe><\/div>\n<p>&nbsp;<br \/>\nMit diesem Video m\u00f6chte sich das gesamte Team von Came bei unseren Kunden und Partnern f\u00fcr ihren Besuch an unserem Stand auf der <a href=\"https:\/\/www.quickfairs.net\/\" target=\"_blank\" rel=\"noopener\">Colitech 2023<\/a>&nbsp;in Pordenone bedanken.<\/p>\n<p>Die Coiltech erwies sich einmal mehr als europ\u00e4ischer Bezugspunkt, um Kunden und Partner zu treffen und sich mit den weltweiten Markttrends zu vergleichen.<\/p>\n<p>An unserem Stand konnten Sie die neuen Dienstleistungen von Came entdecken, wie zum Beispiel:<\/p>\n<ul>\n<li>Die Dienstleistung von Came f\u00fcr die <a href=\"https:\/\/came-italy.com\/it\/i-vantaggi-del-servizio-came-per-il-cost-saving-del-motore-elettrico\/\" target=\"_blank\" rel=\"noopener\">Kostenersparnis eines Elektromotors<\/a><\/li>\n<li>Die Vorteile bei der Herstellung von <a href=\"https:\/\/came-italy.com\/it\/i-vantaggi-del-servizio-came-per-il-cost-saving-del-motore-elettrico\/\" target=\"_blank\" rel=\"noopener\">Motoren ohne Verwendung von Seltenen Erden<\/a><\/li>\n<li>Die Dienstleistung f\u00fcr die&nbsp;<a href=\"https:\/\/came-italy.com\/it\/i-vantaggi-del-servizio-came-per-il-cost-saving-del-motore-elettrico\/\" target=\"_blank\" rel=\"noopener\">Optimierung eines gewickelten Stators<\/a><\/li>\n<\/ul>\n<p>&nbsp;<br \/>\nSie k\u00f6nnen uns erreichen, indem Sie eine E-Mail an&nbsp;<a href=\"mailto:consulting@came-italy.com\">consulting@came-italy.com<\/a>&nbsp;senden oder die Nummer<br \/>\n<a href=\"tel:+39%200444%20488282\">+39 0444 488282<\/a> anrufen.<\/p>\n<p>Wir werden Ihnen gerne die beste L\u00f6sung f\u00fcr Ihr Unternehmen anbieten.<\/p>\n<p>In der Zwischenzeit empfehlen wir Ihnen, alle fachlichen und aktualisierten Artikel in den <a href=\"https:\/\/came-italy.com\/de\/nachrichten\/\" target=\"_blank\" rel=\"noopener\">News von Came<\/a> zu lesen.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&nbsp; Mit diesem Video m\u00f6chte sich das gesamte Team von Came bei unseren Kunden und Partnern f\u00fcr ihren Besuch an unserem Stand auf der Colitech 2023&nbsp;in Pordenone bedanken. Die Coiltech erwies sich einmal mehr als europ\u00e4ischer Bezugspunkt, um Kunden und Partner zu treffen und sich mit den weltweiten Markttrends zu vergleichen. An unserem Stand konnten [&hellip;]<\/p>\n","protected":false},"author":13,"featured_media":15978,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[145],"tags":[],"class_list":["post-15971","post","type-post","status-publish","format-video","has-post-thumbnail","hentry","category-unkategorisiert","post_format-post-format-video"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Vielen Dank f\u00fcr Ihren Besuch bei uns auf der Coiltech Pordenone 2023 - Came Spa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/came-italy.com\/de\/vielen-dank-fuer-ihren-besuch-bei-uns-auf-der-coiltech-pordenone-2023\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Vielen Dank f\u00fcr Ihren Besuch bei uns auf der Coiltech Pordenone 2023 - Came Spa\" \/>\n<meta property=\"og:description\" content=\"&nbsp; Mit diesem Video m\u00f6chte sich das gesamte Team von Came bei unseren Kunden und Partnern f\u00fcr ihren Besuch an unserem Stand auf der Colitech 2023&nbsp;in Pordenone bedanken. Die Coiltech erwies sich einmal mehr als europ\u00e4ischer Bezugspunkt, um Kunden und Partner zu treffen und sich mit den weltweiten Markttrends zu vergleichen. An unserem Stand konnten [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/came-italy.com\/de\/vielen-dank-fuer-ihren-besuch-bei-uns-auf-der-coiltech-pordenone-2023\/\" \/>\n<meta property=\"og:site_name\" content=\"Came Spa\" \/>\n<meta property=\"article:published_time\" content=\"2023-10-05T09:38:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-05T13:38:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/came-italy.com\/wp-content\/uploads\/2023\/10\/came-cover.png\" \/>\n\t<meta property=\"og:image:width\" content=\"854\" \/>\n\t<meta property=\"og:image:height\" content=\"484\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"marijana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"marijana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/came-italy.com\\\/de\\\/vielen-dank-fuer-ihren-besuch-bei-uns-auf-der-coiltech-pordenone-2023\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/came-italy.com\\\/de\\\/vielen-dank-fuer-ihren-besuch-bei-uns-auf-der-coiltech-pordenone-2023\\\/\"},\"author\":{\"name\":\"marijana\",\"@id\":\"https:\\\/\\\/came-italy.com\\\/de\\\/#\\\/schema\\\/person\\\/7ed2982a3ffdaadbfdfedf5565fa1435\"},\"headline\":\"Vielen Dank f\u00fcr Ihren Besuch bei uns auf der Coiltech Pordenone 2023\",\"datePublished\":\"2023-10-05T09:38:16+00:00\",\"dateModified\":\"2023-10-05T13:38:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/came-italy.com\\\/de\\\/vielen-dank-fuer-ihren-besuch-bei-uns-auf-der-coiltech-pordenone-2023\\\/\"},\"wordCount\":165,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/came-italy.com\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/came-italy.com\\\/de\\\/vielen-dank-fuer-ihren-besuch-bei-uns-auf-der-coiltech-pordenone-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/came-italy.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/came-cover.png\",\"articleSection\":[\"Unkategorisiert\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/came-italy.com\\\/de\\\/vielen-dank-fuer-ihren-besuch-bei-uns-auf-der-coiltech-pordenone-2023\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/came-italy.com\\\/de\\\/vielen-dank-fuer-ihren-besuch-bei-uns-auf-der-coiltech-pordenone-2023\\\/\",\"url\":\"https:\\\/\\\/came-italy.com\\\/de\\\/vielen-dank-fuer-ihren-besuch-bei-uns-auf-der-coiltech-pordenone-2023\\\/\",\"name\":\"Vielen Dank f\u00fcr Ihren Besuch bei uns auf der Coiltech Pordenone 2023 - Came Spa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/came-italy.com\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/came-italy.com\\\/de\\\/vielen-dank-fuer-ihren-besuch-bei-uns-auf-der-coiltech-pordenone-2023\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/came-italy.com\\\/de\\\/vielen-dank-fuer-ihren-besuch-bei-uns-auf-der-coiltech-pordenone-2023\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/came-italy.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/came-cover.png\",\"datePublished\":\"2023-10-05T09:38:16+00:00\",\"dateModified\":\"2023-10-05T13:38:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/came-italy.com\\\/de\\\/vielen-dank-fuer-ihren-besuch-bei-uns-auf-der-coiltech-pordenone-2023\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/came-italy.com\\\/de\\\/vielen-dank-fuer-ihren-besuch-bei-uns-auf-der-coiltech-pordenone-2023\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/came-italy.com\\\/de\\\/vielen-dank-fuer-ihren-besuch-bei-uns-auf-der-coiltech-pordenone-2023\\\/#primaryimage\",\"url\":\"https:\\\/\\\/came-italy.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/came-cover.png\",\"contentUrl\":\"https:\\\/\\\/came-italy.com\\\/wp-content\\\/uploads\\\/2023\\\/10\\\/came-cover.png\",\"width\":854,\"height\":484},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/came-italy.com\\\/de\\\/vielen-dank-fuer-ihren-besuch-bei-uns-auf-der-coiltech-pordenone-2023\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/came-italy.com\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Vielen Dank f\u00fcr Ihren Besuch bei uns auf der Coiltech Pordenone 2023\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/came-italy.com\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/came-italy.com\\\/de\\\/\",\"name\":\"Came Spa\",\"description\":\"Avvolgimenti e componenti per motori elettrici\",\"publisher\":{\"@id\":\"https:\\\/\\\/came-italy.com\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/came-italy.com\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/came-italy.com\\\/de\\\/#organization\",\"name\":\"Came Spa\",\"url\":\"https:\\\/\\\/came-italy.com\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/came-italy.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/came-italy.com\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/logo-came-spa.png\",\"contentUrl\":\"https:\\\/\\\/came-italy.com\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/logo-came-spa.png\",\"width\":766,\"height\":129,\"caption\":\"Came Spa\"},\"image\":{\"@id\":\"https:\\\/\\\/came-italy.com\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/came-italy.com\\\/de\\\/#\\\/schema\\\/person\\\/7ed2982a3ffdaadbfdfedf5565fa1435\",\"name\":\"marijana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ee78faab5826f03303aab7c47d47183397de12c018a1326dd7b56f1b1cd2002?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ee78faab5826f03303aab7c47d47183397de12c018a1326dd7b56f1b1cd2002?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ee78faab5826f03303aab7c47d47183397de12c018a1326dd7b56f1b1cd2002?s=96&d=mm&r=g\",\"caption\":\"marijana\"},\"url\":\"https:\\\/\\\/came-italy.com\\\/de\\\/author\\\/marijana\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Vielen Dank f\u00fcr Ihren Besuch bei uns auf der Coiltech Pordenone 2023 - Came Spa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/came-italy.com\/de\/vielen-dank-fuer-ihren-besuch-bei-uns-auf-der-coiltech-pordenone-2023\/","og_locale":"de_DE","og_type":"article","og_title":"Vielen Dank f\u00fcr Ihren Besuch bei uns auf der Coiltech Pordenone 2023 - Came Spa","og_description":"&nbsp; Mit diesem Video m\u00f6chte sich das gesamte Team von Came bei unseren Kunden und Partnern f\u00fcr ihren Besuch an unserem Stand auf der Colitech 2023&nbsp;in Pordenone bedanken. Die Coiltech erwies sich einmal mehr als europ\u00e4ischer Bezugspunkt, um Kunden und Partner zu treffen und sich mit den weltweiten Markttrends zu vergleichen. An unserem Stand konnten [&hellip;]","og_url":"https:\/\/came-italy.com\/de\/vielen-dank-fuer-ihren-besuch-bei-uns-auf-der-coiltech-pordenone-2023\/","og_site_name":"Came Spa","article_published_time":"2023-10-05T09:38:16+00:00","article_modified_time":"2023-10-05T13:38:25+00:00","og_image":[{"width":854,"height":484,"url":"https:\/\/came-italy.com\/wp-content\/uploads\/2023\/10\/came-cover.png","type":"image\/png"}],"author":"marijana","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"marijana","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/came-italy.com\/de\/vielen-dank-fuer-ihren-besuch-bei-uns-auf-der-coiltech-pordenone-2023\/#article","isPartOf":{"@id":"https:\/\/came-italy.com\/de\/vielen-dank-fuer-ihren-besuch-bei-uns-auf-der-coiltech-pordenone-2023\/"},"author":{"name":"marijana","@id":"https:\/\/came-italy.com\/de\/#\/schema\/person\/7ed2982a3ffdaadbfdfedf5565fa1435"},"headline":"Vielen Dank f\u00fcr Ihren Besuch bei uns auf der Coiltech Pordenone 2023","datePublished":"2023-10-05T09:38:16+00:00","dateModified":"2023-10-05T13:38:25+00:00","mainEntityOfPage":{"@id":"https:\/\/came-italy.com\/de\/vielen-dank-fuer-ihren-besuch-bei-uns-auf-der-coiltech-pordenone-2023\/"},"wordCount":165,"commentCount":0,"publisher":{"@id":"https:\/\/came-italy.com\/de\/#organization"},"image":{"@id":"https:\/\/came-italy.com\/de\/vielen-dank-fuer-ihren-besuch-bei-uns-auf-der-coiltech-pordenone-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/came-italy.com\/wp-content\/uploads\/2023\/10\/came-cover.png","articleSection":["Unkategorisiert"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/came-italy.com\/de\/vielen-dank-fuer-ihren-besuch-bei-uns-auf-der-coiltech-pordenone-2023\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/came-italy.com\/de\/vielen-dank-fuer-ihren-besuch-bei-uns-auf-der-coiltech-pordenone-2023\/","url":"https:\/\/came-italy.com\/de\/vielen-dank-fuer-ihren-besuch-bei-uns-auf-der-coiltech-pordenone-2023\/","name":"Vielen Dank f\u00fcr Ihren Besuch bei uns auf der Coiltech Pordenone 2023 - Came Spa","isPartOf":{"@id":"https:\/\/came-italy.com\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/came-italy.com\/de\/vielen-dank-fuer-ihren-besuch-bei-uns-auf-der-coiltech-pordenone-2023\/#primaryimage"},"image":{"@id":"https:\/\/came-italy.com\/de\/vielen-dank-fuer-ihren-besuch-bei-uns-auf-der-coiltech-pordenone-2023\/#primaryimage"},"thumbnailUrl":"https:\/\/came-italy.com\/wp-content\/uploads\/2023\/10\/came-cover.png","datePublished":"2023-10-05T09:38:16+00:00","dateModified":"2023-10-05T13:38:25+00:00","breadcrumb":{"@id":"https:\/\/came-italy.com\/de\/vielen-dank-fuer-ihren-besuch-bei-uns-auf-der-coiltech-pordenone-2023\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/came-italy.com\/de\/vielen-dank-fuer-ihren-besuch-bei-uns-auf-der-coiltech-pordenone-2023\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/came-italy.com\/de\/vielen-dank-fuer-ihren-besuch-bei-uns-auf-der-coiltech-pordenone-2023\/#primaryimage","url":"https:\/\/came-italy.com\/wp-content\/uploads\/2023\/10\/came-cover.png","contentUrl":"https:\/\/came-italy.com\/wp-content\/uploads\/2023\/10\/came-cover.png","width":854,"height":484},{"@type":"BreadcrumbList","@id":"https:\/\/came-italy.com\/de\/vielen-dank-fuer-ihren-besuch-bei-uns-auf-der-coiltech-pordenone-2023\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/came-italy.com\/de\/"},{"@type":"ListItem","position":2,"name":"Vielen Dank f\u00fcr Ihren Besuch bei uns auf der Coiltech Pordenone 2023"}]},{"@type":"WebSite","@id":"https:\/\/came-italy.com\/de\/#website","url":"https:\/\/came-italy.com\/de\/","name":"Came Spa","description":"Avvolgimenti e componenti per motori elettrici","publisher":{"@id":"https:\/\/came-italy.com\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/came-italy.com\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/came-italy.com\/de\/#organization","name":"Came Spa","url":"https:\/\/came-italy.com\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/came-italy.com\/de\/#\/schema\/logo\/image\/","url":"https:\/\/came-italy.com\/wp-content\/uploads\/2016\/07\/logo-came-spa.png","contentUrl":"https:\/\/came-italy.com\/wp-content\/uploads\/2016\/07\/logo-came-spa.png","width":766,"height":129,"caption":"Came Spa"},"image":{"@id":"https:\/\/came-italy.com\/de\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/came-italy.com\/de\/#\/schema\/person\/7ed2982a3ffdaadbfdfedf5565fa1435","name":"marijana","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/7ee78faab5826f03303aab7c47d47183397de12c018a1326dd7b56f1b1cd2002?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7ee78faab5826f03303aab7c47d47183397de12c018a1326dd7b56f1b1cd2002?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7ee78faab5826f03303aab7c47d47183397de12c018a1326dd7b56f1b1cd2002?s=96&d=mm&r=g","caption":"marijana"},"url":"https:\/\/came-italy.com\/de\/author\/marijana\/"}]}},"_links":{"self":[{"href":"https:\/\/came-italy.com\/de\/wp-json\/wp\/v2\/posts\/15971","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/came-italy.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/came-italy.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/came-italy.com\/de\/wp-json\/wp\/v2\/users\/13"}],"replies":[{"embeddable":true,"href":"https:\/\/came-italy.com\/de\/wp-json\/wp\/v2\/comments?post=15971"}],"version-history":[{"count":3,"href":"https:\/\/came-italy.com\/de\/wp-json\/wp\/v2\/posts\/15971\/revisions"}],"predecessor-version":[{"id":15982,"href":"https:\/\/came-italy.com\/de\/wp-json\/wp\/v2\/posts\/15971\/revisions\/15982"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/came-italy.com\/de\/wp-json\/wp\/v2\/media\/15978"}],"wp:attachment":[{"href":"https:\/\/came-italy.com\/de\/wp-json\/wp\/v2\/media?parent=15971"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/came-italy.com\/de\/wp-json\/wp\/v2\/categories?post=15971"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/came-italy.com\/de\/wp-json\/wp\/v2\/tags?post=15971"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}