{"id":12079,"date":"2021-02-19T08:41:21","date_gmt":"2021-02-19T07:41:21","guid":{"rendered":"https:\/\/came-italy.com\/?p=12079"},"modified":"2021-02-19T08:41:21","modified_gmt":"2021-02-19T07:41:21","slug":"came-cerca-due-candidati-grazie-al-bando-del-comune-di-altissimo","status":"publish","type":"post","link":"https:\/\/came-italy.com\/it\/came-cerca-due-candidati-grazie-al-bando-del-comune-di-altissimo\/","title":{"rendered":"Came cerca due candidati grazie al bando del Comune di Altissimo"},"content":{"rendered":"<p>Came cerca due candidati in merito all&#8217;adesione al bando per il sostegno all&#8217;occupazione <a href=\"http:\/\/www.comune.altissimo.vi.it\/default.asp\">del Comune di Altissimo<\/a>.<\/p>\n<p>Il bando nasce dal Comune di Altissimo per aiutare a risolvere la crisi derivata dal Covid19 e ha come finalit\u00e0 l&#8217;incentivo all&#8217;occupazione delle imprese che abbiano all&#8217;attivo o attivino contratti con cittadini residenti nel territorio del Comune di Altissimo.<\/p>\n<p><a href=\"http:\/\/www.comune.altissimo.vi.it\/dett.asp?id_doc=79646\" rel=\"noopener\" target=\"_blank\">I dettagli del bando possono essere letti a questo link.<\/a><\/p>\n<p>Se siete cittadini del Comune di Altissimo e volete fare parte del team Came potete candidarvi <a href=\"http:\/\/www.comune.altissimo.vi.it\/dett.asp?id_doc=79646\" rel=\"noopener\" target=\"_blank\">seguendo le modalit\u00e0 indicate nel bando sul sito del Comune di Altissimo che trovate a questo link<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Came cerca due candidati in merito all&#8217;adesione al bando per il sostegno all&#8217;occupazione del Comune di Altissimo. Il bando nasce dal Comune di Altissimo per aiutare a risolvere la crisi derivata dal Covid19 e ha come finalit\u00e0 l&#8217;incentivo all&#8217;occupazione delle imprese che abbiano all&#8217;attivo o attivino contratti con cittadini residenti nel territorio del Comune di [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":12080,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[3],"tags":[],"class_list":["post-12079","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-corporate"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Came cerca due candidati grazie al bando del Comune di Altissimo - Came Spa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/came-italy.com\/it\/came-cerca-due-candidati-grazie-al-bando-del-comune-di-altissimo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Came cerca due candidati grazie al bando del Comune di Altissimo - Came Spa\" \/>\n<meta property=\"og:description\" content=\"Came cerca due candidati in merito all&#8217;adesione al bando per il sostegno all&#8217;occupazione del Comune di Altissimo. Il bando nasce dal Comune di Altissimo per aiutare a risolvere la crisi derivata dal Covid19 e ha come finalit\u00e0 l&#8217;incentivo all&#8217;occupazione delle imprese che abbiano all&#8217;attivo o attivino contratti con cittadini residenti nel territorio del Comune di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/came-italy.com\/it\/came-cerca-due-candidati-grazie-al-bando-del-comune-di-altissimo\/\" \/>\n<meta property=\"og:site_name\" content=\"Came Spa\" \/>\n<meta property=\"article:published_time\" content=\"2021-02-19T07:41:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/came-italy.com\/wp-content\/uploads\/2021\/02\/Bando.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andrea Toniolo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andrea Toniolo\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/came-italy.com\\\/it\\\/came-cerca-due-candidati-grazie-al-bando-del-comune-di-altissimo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/came-italy.com\\\/it\\\/came-cerca-due-candidati-grazie-al-bando-del-comune-di-altissimo\\\/\"},\"author\":{\"name\":\"Andrea Toniolo\",\"@id\":\"https:\\\/\\\/came-italy.com\\\/it\\\/#\\\/schema\\\/person\\\/da677687caf9ad54b55d15c77d264d7c\"},\"headline\":\"Came cerca due candidati grazie al bando del Comune di Altissimo\",\"datePublished\":\"2021-02-19T07:41:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/came-italy.com\\\/it\\\/came-cerca-due-candidati-grazie-al-bando-del-comune-di-altissimo\\\/\"},\"wordCount\":115,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/came-italy.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/came-italy.com\\\/it\\\/came-cerca-due-candidati-grazie-al-bando-del-comune-di-altissimo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/came-italy.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Bando.jpg\",\"articleSection\":[\"Corporate\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/came-italy.com\\\/it\\\/came-cerca-due-candidati-grazie-al-bando-del-comune-di-altissimo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/came-italy.com\\\/it\\\/came-cerca-due-candidati-grazie-al-bando-del-comune-di-altissimo\\\/\",\"url\":\"https:\\\/\\\/came-italy.com\\\/it\\\/came-cerca-due-candidati-grazie-al-bando-del-comune-di-altissimo\\\/\",\"name\":\"Came cerca due candidati grazie al bando del Comune di Altissimo - Came Spa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/came-italy.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/came-italy.com\\\/it\\\/came-cerca-due-candidati-grazie-al-bando-del-comune-di-altissimo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/came-italy.com\\\/it\\\/came-cerca-due-candidati-grazie-al-bando-del-comune-di-altissimo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/came-italy.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Bando.jpg\",\"datePublished\":\"2021-02-19T07:41:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/came-italy.com\\\/it\\\/came-cerca-due-candidati-grazie-al-bando-del-comune-di-altissimo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/came-italy.com\\\/it\\\/came-cerca-due-candidati-grazie-al-bando-del-comune-di-altissimo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/came-italy.com\\\/it\\\/came-cerca-due-candidati-grazie-al-bando-del-comune-di-altissimo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/came-italy.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Bando.jpg\",\"contentUrl\":\"https:\\\/\\\/came-italy.com\\\/wp-content\\\/uploads\\\/2021\\\/02\\\/Bando.jpg\",\"width\":850,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/came-italy.com\\\/it\\\/came-cerca-due-candidati-grazie-al-bando-del-comune-di-altissimo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/came-italy.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Came cerca due candidati grazie al bando del Comune di Altissimo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/came-italy.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/came-italy.com\\\/it\\\/\",\"name\":\"Came Spa\",\"description\":\"Avvolgimenti e componenti per motori elettrici\",\"publisher\":{\"@id\":\"https:\\\/\\\/came-italy.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/came-italy.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/came-italy.com\\\/it\\\/#organization\",\"name\":\"Came Spa\",\"url\":\"https:\\\/\\\/came-italy.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/came-italy.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/came-italy.com\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/logo-came-spa.png\",\"contentUrl\":\"https:\\\/\\\/came-italy.com\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/logo-came-spa.png\",\"width\":766,\"height\":129,\"caption\":\"Came Spa\"},\"image\":{\"@id\":\"https:\\\/\\\/came-italy.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/came-italy.com\\\/it\\\/#\\\/schema\\\/person\\\/da677687caf9ad54b55d15c77d264d7c\",\"name\":\"Andrea Toniolo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e1912c0d135981b2b041c8e10cbcfb1463c1fd2a779fcae4dd31d8add9c64804?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e1912c0d135981b2b041c8e10cbcfb1463c1fd2a779fcae4dd31d8add9c64804?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e1912c0d135981b2b041c8e10cbcfb1463c1fd2a779fcae4dd31d8add9c64804?s=96&d=mm&r=g\",\"caption\":\"Andrea Toniolo\"},\"url\":\"https:\\\/\\\/came-italy.com\\\/it\\\/author\\\/andrea\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Came cerca due candidati grazie al bando del Comune di Altissimo - Came Spa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/came-italy.com\/it\/came-cerca-due-candidati-grazie-al-bando-del-comune-di-altissimo\/","og_locale":"it_IT","og_type":"article","og_title":"Came cerca due candidati grazie al bando del Comune di Altissimo - Came Spa","og_description":"Came cerca due candidati in merito all&#8217;adesione al bando per il sostegno all&#8217;occupazione del Comune di Altissimo. Il bando nasce dal Comune di Altissimo per aiutare a risolvere la crisi derivata dal Covid19 e ha come finalit\u00e0 l&#8217;incentivo all&#8217;occupazione delle imprese che abbiano all&#8217;attivo o attivino contratti con cittadini residenti nel territorio del Comune di [&hellip;]","og_url":"https:\/\/came-italy.com\/it\/came-cerca-due-candidati-grazie-al-bando-del-comune-di-altissimo\/","og_site_name":"Came Spa","article_published_time":"2021-02-19T07:41:21+00:00","og_image":[{"width":850,"height":450,"url":"https:\/\/came-italy.com\/wp-content\/uploads\/2021\/02\/Bando.jpg","type":"image\/jpeg"}],"author":"Andrea Toniolo","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Andrea Toniolo"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/came-italy.com\/it\/came-cerca-due-candidati-grazie-al-bando-del-comune-di-altissimo\/#article","isPartOf":{"@id":"https:\/\/came-italy.com\/it\/came-cerca-due-candidati-grazie-al-bando-del-comune-di-altissimo\/"},"author":{"name":"Andrea Toniolo","@id":"https:\/\/came-italy.com\/it\/#\/schema\/person\/da677687caf9ad54b55d15c77d264d7c"},"headline":"Came cerca due candidati grazie al bando del Comune di Altissimo","datePublished":"2021-02-19T07:41:21+00:00","mainEntityOfPage":{"@id":"https:\/\/came-italy.com\/it\/came-cerca-due-candidati-grazie-al-bando-del-comune-di-altissimo\/"},"wordCount":115,"commentCount":0,"publisher":{"@id":"https:\/\/came-italy.com\/it\/#organization"},"image":{"@id":"https:\/\/came-italy.com\/it\/came-cerca-due-candidati-grazie-al-bando-del-comune-di-altissimo\/#primaryimage"},"thumbnailUrl":"https:\/\/came-italy.com\/wp-content\/uploads\/2021\/02\/Bando.jpg","articleSection":["Corporate"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/came-italy.com\/it\/came-cerca-due-candidati-grazie-al-bando-del-comune-di-altissimo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/came-italy.com\/it\/came-cerca-due-candidati-grazie-al-bando-del-comune-di-altissimo\/","url":"https:\/\/came-italy.com\/it\/came-cerca-due-candidati-grazie-al-bando-del-comune-di-altissimo\/","name":"Came cerca due candidati grazie al bando del Comune di Altissimo - Came Spa","isPartOf":{"@id":"https:\/\/came-italy.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/came-italy.com\/it\/came-cerca-due-candidati-grazie-al-bando-del-comune-di-altissimo\/#primaryimage"},"image":{"@id":"https:\/\/came-italy.com\/it\/came-cerca-due-candidati-grazie-al-bando-del-comune-di-altissimo\/#primaryimage"},"thumbnailUrl":"https:\/\/came-italy.com\/wp-content\/uploads\/2021\/02\/Bando.jpg","datePublished":"2021-02-19T07:41:21+00:00","breadcrumb":{"@id":"https:\/\/came-italy.com\/it\/came-cerca-due-candidati-grazie-al-bando-del-comune-di-altissimo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/came-italy.com\/it\/came-cerca-due-candidati-grazie-al-bando-del-comune-di-altissimo\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/came-italy.com\/it\/came-cerca-due-candidati-grazie-al-bando-del-comune-di-altissimo\/#primaryimage","url":"https:\/\/came-italy.com\/wp-content\/uploads\/2021\/02\/Bando.jpg","contentUrl":"https:\/\/came-italy.com\/wp-content\/uploads\/2021\/02\/Bando.jpg","width":850,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/came-italy.com\/it\/came-cerca-due-candidati-grazie-al-bando-del-comune-di-altissimo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/came-italy.com\/it\/"},{"@type":"ListItem","position":2,"name":"Came cerca due candidati grazie al bando del Comune di Altissimo"}]},{"@type":"WebSite","@id":"https:\/\/came-italy.com\/it\/#website","url":"https:\/\/came-italy.com\/it\/","name":"Came Spa","description":"Avvolgimenti e componenti per motori elettrici","publisher":{"@id":"https:\/\/came-italy.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/came-italy.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/came-italy.com\/it\/#organization","name":"Came Spa","url":"https:\/\/came-italy.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/came-italy.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/came-italy.com\/wp-content\/uploads\/2016\/07\/logo-came-spa.png","contentUrl":"https:\/\/came-italy.com\/wp-content\/uploads\/2016\/07\/logo-came-spa.png","width":766,"height":129,"caption":"Came Spa"},"image":{"@id":"https:\/\/came-italy.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/came-italy.com\/it\/#\/schema\/person\/da677687caf9ad54b55d15c77d264d7c","name":"Andrea Toniolo","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/e1912c0d135981b2b041c8e10cbcfb1463c1fd2a779fcae4dd31d8add9c64804?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e1912c0d135981b2b041c8e10cbcfb1463c1fd2a779fcae4dd31d8add9c64804?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e1912c0d135981b2b041c8e10cbcfb1463c1fd2a779fcae4dd31d8add9c64804?s=96&d=mm&r=g","caption":"Andrea Toniolo"},"url":"https:\/\/came-italy.com\/it\/author\/andrea\/"}]}},"_links":{"self":[{"href":"https:\/\/came-italy.com\/it\/wp-json\/wp\/v2\/posts\/12079","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/came-italy.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/came-italy.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/came-italy.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/came-italy.com\/it\/wp-json\/wp\/v2\/comments?post=12079"}],"version-history":[{"count":3,"href":"https:\/\/came-italy.com\/it\/wp-json\/wp\/v2\/posts\/12079\/revisions"}],"predecessor-version":[{"id":12086,"href":"https:\/\/came-italy.com\/it\/wp-json\/wp\/v2\/posts\/12079\/revisions\/12086"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/came-italy.com\/it\/wp-json\/wp\/v2\/media\/12080"}],"wp:attachment":[{"href":"https:\/\/came-italy.com\/it\/wp-json\/wp\/v2\/media?parent=12079"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/came-italy.com\/it\/wp-json\/wp\/v2\/categories?post=12079"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/came-italy.com\/it\/wp-json\/wp\/v2\/tags?post=12079"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}