{"id":13528,"date":"2022-05-05T11:29:04","date_gmt":"2022-05-05T09:29:04","guid":{"rendered":"https:\/\/came-italy.com\/?p=13528"},"modified":"2022-05-05T11:29:04","modified_gmt":"2022-05-05T09:29:04","slug":"la-collaborazione-tra-came-e-cliente-per-il-progetto-di-nuovo-motore-per-pompe-idrauliche","status":"publish","type":"post","link":"https:\/\/came-italy.com\/it\/la-collaborazione-tra-came-e-cliente-per-il-progetto-di-nuovo-motore-per-pompe-idrauliche\/","title":{"rendered":"La collaborazione tra Came e cliente per il progetto di nuovo motore per pompe idrauliche"},"content":{"rendered":"<p>Durante il 2020 un azienda leader globale nella realizzazione di pompe idrauliche, ha richiesto a Came la progettazione di un nuovo tipo di avvolgimento per una pompa ad alta efficienza con stringenti requisiti a livello di tolleranze, CSR e capitolati tecnici.<\/p>\n<p>Il progetto ha richiesto <a href=\"https:\/\/came-italy.com\/it\/i-servizi-came-per-dare-soluzioni-al-cliente\/\" target=\"_blank\" rel=\"noopener\">tutta l&#8217;esperienza e il know-how di Came<\/a> nella combinazione di pressofusione e avvolgimenti per <a href=\"https:\/\/came-italy.com\/it\/i-benefici-per-i-clienti-del-servizio-came-rd-presentati-nel-nostro-nuovo-video\/\" target=\"_blank\" rel=\"noopener\">risolvere la sfida tecnica di un prodotto innovativo e complesso<\/a>.<\/p>\n<p>Durante i 2 anni di progetto \u00e8 stato richiesto un forte focus <a href=\"https:\/\/came-italy.com\/it\/il-nuovo-video-came-aluminium-die-casting\/\" target=\"_blank\" rel=\"noopener\">nel design del pressofuso<\/a> per le taglie del motore Mec 90-112-132, richiedendo la progettazione di 4 pressofusi e 9 avvolgimenti diversi dovendo combinare le richieste di design alle necessit\u00e0 produttive di Came.<\/p>\n<p>Tutto il team Came \u00e8 stato coinvolto in una stretta collaborazione con il team del cliente, lavorando con costanti allineamenti tecnici per un progetto che ha richiesto una reale integrazione tra le due realt\u00e0, dovendo i team rispettare un gantt di progetto puntuale.<\/p>\n<p>Abbiamo suggerito al cliente un innovativo processo di isolamento della guarnizione del prodotto che includeva l&#8217;uso di una nuova tecnologia a base di schiuma che ha permesso di otimizzare il montaggio del prodotto e abbatterne i costi di produzione.<\/p>\n<p>Il lavoro svolto da Came si \u00e8 spinto inoltre alla gestione del capo commessa con la fornitura di statore avvolto e per le varie fasi esterne necessarie all\u2019ottenimento dell\u2019assemblato finito.<\/p>\n<p>Qui riassumiamo i vantaggi che il cliente ha potuto ottenere dalla collaborazione con Came:<br \/>\n&#8211; Consulenza tecnica completa<br \/>\n&#8211; Affidabilit\u00e0 del team di lavoro dedicato<br \/>\n&#8211; Co-design di pressofusi e avvolgimenti<br \/>\n&#8211; Supply chain ridotta<br \/>\n&#8211; Cost saving del prodotto<\/p>\n<p>La sinergia tra Came e cliente \u00e8 stata un successo e la dimostrazione che <a href=\"https:\/\/came-italy.com\/it\/il-piano-di-sviluppo-delle-risorse-umane-il-capitale-di-came\/\" target=\"_blank\" rel=\"noopener\">il lavoro di squadra<\/a>, i valori e il know-how sono elementi necessari per ottenere risultati importanti.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante il 2020 un azienda leader globale nella realizzazione di pompe idrauliche, ha richiesto a Came la progettazione di un nuovo tipo di avvolgimento per una pompa ad alta efficienza con stringenti requisiti a livello di tolleranze, CSR e capitolati tecnici. Il progetto ha richiesto tutta l&#8217;esperienza e il know-how di Came nella combinazione di [&hellip;]<\/p>\n","protected":false},"author":6,"featured_media":13666,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[3,578,5,6],"tags":[18,541,699,737,739,738,740,362,416],"class_list":["post-13528","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-corporate","category-die-casting","category-prodotti","category-ricerca-e-sviluppo","tag-avvolgimenti","tag-came-die-casting-2","tag-co-design","tag-consulenza","tag-cost-saving-di-prodotto","tag-guarnizione","tag-pompe-idrauliche","tag-pressofusione","tag-supply-chain"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.3 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La collaborazione tra Came e cliente per il progetto di nuovo motore per pompe idrauliche - Came Spa<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/came-italy.com\/it\/la-collaborazione-tra-came-e-cliente-per-il-progetto-di-nuovo-motore-per-pompe-idrauliche\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La collaborazione tra Came e cliente per il progetto di nuovo motore per pompe idrauliche - Came Spa\" \/>\n<meta property=\"og:description\" content=\"Durante il 2020 un azienda leader globale nella realizzazione di pompe idrauliche, ha richiesto a Came la progettazione di un nuovo tipo di avvolgimento per una pompa ad alta efficienza con stringenti requisiti a livello di tolleranze, CSR e capitolati tecnici. Il progetto ha richiesto tutta l&#8217;esperienza e il know-how di Came nella combinazione di [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/came-italy.com\/it\/la-collaborazione-tra-came-e-cliente-per-il-progetto-di-nuovo-motore-per-pompe-idrauliche\/\" \/>\n<meta property=\"og:site_name\" content=\"Came Spa\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-05T09:29:04+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/came-italy.com\/wp-content\/uploads\/2022\/05\/La-collaborazione-tra-Came-e-cliente.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"850\" \/>\n\t<meta property=\"og:image:height\" content=\"450\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andrea Toniolo\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andrea Toniolo\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/came-italy.com\\\/it\\\/la-collaborazione-tra-came-e-cliente-per-il-progetto-di-nuovo-motore-per-pompe-idrauliche\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/came-italy.com\\\/it\\\/la-collaborazione-tra-came-e-cliente-per-il-progetto-di-nuovo-motore-per-pompe-idrauliche\\\/\"},\"author\":{\"name\":\"Andrea Toniolo\",\"@id\":\"https:\\\/\\\/came-italy.com\\\/it\\\/#\\\/schema\\\/person\\\/da677687caf9ad54b55d15c77d264d7c\"},\"headline\":\"La collaborazione tra Came e cliente per il progetto di nuovo motore per pompe idrauliche\",\"datePublished\":\"2022-05-05T09:29:04+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/came-italy.com\\\/it\\\/la-collaborazione-tra-came-e-cliente-per-il-progetto-di-nuovo-motore-per-pompe-idrauliche\\\/\"},\"wordCount\":307,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/came-italy.com\\\/it\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/came-italy.com\\\/it\\\/la-collaborazione-tra-came-e-cliente-per-il-progetto-di-nuovo-motore-per-pompe-idrauliche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/came-italy.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/La-collaborazione-tra-Came-e-cliente.jpg\",\"keywords\":[\"avvolgimenti\",\"Came die-casting\",\"co-design\",\"Consulenza\",\"Cost saving di prodotto\",\"Guarnizione\",\"Pompe idrauliche\",\"pressofusione\",\"supply chain\"],\"articleSection\":[\"Corporate\",\"Die-Casting\",\"Prodotti\",\"Ricerca e sviluppo\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/came-italy.com\\\/it\\\/la-collaborazione-tra-came-e-cliente-per-il-progetto-di-nuovo-motore-per-pompe-idrauliche\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/came-italy.com\\\/it\\\/la-collaborazione-tra-came-e-cliente-per-il-progetto-di-nuovo-motore-per-pompe-idrauliche\\\/\",\"url\":\"https:\\\/\\\/came-italy.com\\\/it\\\/la-collaborazione-tra-came-e-cliente-per-il-progetto-di-nuovo-motore-per-pompe-idrauliche\\\/\",\"name\":\"La collaborazione tra Came e cliente per il progetto di nuovo motore per pompe idrauliche - Came Spa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/came-italy.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/came-italy.com\\\/it\\\/la-collaborazione-tra-came-e-cliente-per-il-progetto-di-nuovo-motore-per-pompe-idrauliche\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/came-italy.com\\\/it\\\/la-collaborazione-tra-came-e-cliente-per-il-progetto-di-nuovo-motore-per-pompe-idrauliche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/came-italy.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/La-collaborazione-tra-Came-e-cliente.jpg\",\"datePublished\":\"2022-05-05T09:29:04+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/came-italy.com\\\/it\\\/la-collaborazione-tra-came-e-cliente-per-il-progetto-di-nuovo-motore-per-pompe-idrauliche\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/came-italy.com\\\/it\\\/la-collaborazione-tra-came-e-cliente-per-il-progetto-di-nuovo-motore-per-pompe-idrauliche\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/came-italy.com\\\/it\\\/la-collaborazione-tra-came-e-cliente-per-il-progetto-di-nuovo-motore-per-pompe-idrauliche\\\/#primaryimage\",\"url\":\"https:\\\/\\\/came-italy.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/La-collaborazione-tra-Came-e-cliente.jpg\",\"contentUrl\":\"https:\\\/\\\/came-italy.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/La-collaborazione-tra-Came-e-cliente.jpg\",\"width\":850,\"height\":450},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/came-italy.com\\\/it\\\/la-collaborazione-tra-came-e-cliente-per-il-progetto-di-nuovo-motore-per-pompe-idrauliche\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/came-italy.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La collaborazione tra Came e cliente per il progetto di nuovo motore per pompe idrauliche\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/came-italy.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/came-italy.com\\\/it\\\/\",\"name\":\"Came Spa\",\"description\":\"Avvolgimenti e componenti per motori elettrici\",\"publisher\":{\"@id\":\"https:\\\/\\\/came-italy.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/came-italy.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/came-italy.com\\\/it\\\/#organization\",\"name\":\"Came Spa\",\"url\":\"https:\\\/\\\/came-italy.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/came-italy.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/came-italy.com\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/logo-came-spa.png\",\"contentUrl\":\"https:\\\/\\\/came-italy.com\\\/wp-content\\\/uploads\\\/2016\\\/07\\\/logo-came-spa.png\",\"width\":766,\"height\":129,\"caption\":\"Came Spa\"},\"image\":{\"@id\":\"https:\\\/\\\/came-italy.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/came-italy.com\\\/it\\\/#\\\/schema\\\/person\\\/da677687caf9ad54b55d15c77d264d7c\",\"name\":\"Andrea Toniolo\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e1912c0d135981b2b041c8e10cbcfb1463c1fd2a779fcae4dd31d8add9c64804?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e1912c0d135981b2b041c8e10cbcfb1463c1fd2a779fcae4dd31d8add9c64804?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e1912c0d135981b2b041c8e10cbcfb1463c1fd2a779fcae4dd31d8add9c64804?s=96&d=mm&r=g\",\"caption\":\"Andrea Toniolo\"},\"url\":\"https:\\\/\\\/came-italy.com\\\/it\\\/author\\\/andrea\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La collaborazione tra Came e cliente per il progetto di nuovo motore per pompe idrauliche - Came Spa","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/came-italy.com\/it\/la-collaborazione-tra-came-e-cliente-per-il-progetto-di-nuovo-motore-per-pompe-idrauliche\/","og_locale":"it_IT","og_type":"article","og_title":"La collaborazione tra Came e cliente per il progetto di nuovo motore per pompe idrauliche - Came Spa","og_description":"Durante il 2020 un azienda leader globale nella realizzazione di pompe idrauliche, ha richiesto a Came la progettazione di un nuovo tipo di avvolgimento per una pompa ad alta efficienza con stringenti requisiti a livello di tolleranze, CSR e capitolati tecnici. Il progetto ha richiesto tutta l&#8217;esperienza e il know-how di Came nella combinazione di [&hellip;]","og_url":"https:\/\/came-italy.com\/it\/la-collaborazione-tra-came-e-cliente-per-il-progetto-di-nuovo-motore-per-pompe-idrauliche\/","og_site_name":"Came Spa","article_published_time":"2022-05-05T09:29:04+00:00","og_image":[{"width":850,"height":450,"url":"https:\/\/came-italy.com\/wp-content\/uploads\/2022\/05\/La-collaborazione-tra-Came-e-cliente.jpg","type":"image\/jpeg"}],"author":"Andrea Toniolo","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Andrea Toniolo","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/came-italy.com\/it\/la-collaborazione-tra-came-e-cliente-per-il-progetto-di-nuovo-motore-per-pompe-idrauliche\/#article","isPartOf":{"@id":"https:\/\/came-italy.com\/it\/la-collaborazione-tra-came-e-cliente-per-il-progetto-di-nuovo-motore-per-pompe-idrauliche\/"},"author":{"name":"Andrea Toniolo","@id":"https:\/\/came-italy.com\/it\/#\/schema\/person\/da677687caf9ad54b55d15c77d264d7c"},"headline":"La collaborazione tra Came e cliente per il progetto di nuovo motore per pompe idrauliche","datePublished":"2022-05-05T09:29:04+00:00","mainEntityOfPage":{"@id":"https:\/\/came-italy.com\/it\/la-collaborazione-tra-came-e-cliente-per-il-progetto-di-nuovo-motore-per-pompe-idrauliche\/"},"wordCount":307,"commentCount":0,"publisher":{"@id":"https:\/\/came-italy.com\/it\/#organization"},"image":{"@id":"https:\/\/came-italy.com\/it\/la-collaborazione-tra-came-e-cliente-per-il-progetto-di-nuovo-motore-per-pompe-idrauliche\/#primaryimage"},"thumbnailUrl":"https:\/\/came-italy.com\/wp-content\/uploads\/2022\/05\/La-collaborazione-tra-Came-e-cliente.jpg","keywords":["avvolgimenti","Came die-casting","co-design","Consulenza","Cost saving di prodotto","Guarnizione","Pompe idrauliche","pressofusione","supply chain"],"articleSection":["Corporate","Die-Casting","Prodotti","Ricerca e sviluppo"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/came-italy.com\/it\/la-collaborazione-tra-came-e-cliente-per-il-progetto-di-nuovo-motore-per-pompe-idrauliche\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/came-italy.com\/it\/la-collaborazione-tra-came-e-cliente-per-il-progetto-di-nuovo-motore-per-pompe-idrauliche\/","url":"https:\/\/came-italy.com\/it\/la-collaborazione-tra-came-e-cliente-per-il-progetto-di-nuovo-motore-per-pompe-idrauliche\/","name":"La collaborazione tra Came e cliente per il progetto di nuovo motore per pompe idrauliche - Came Spa","isPartOf":{"@id":"https:\/\/came-italy.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/came-italy.com\/it\/la-collaborazione-tra-came-e-cliente-per-il-progetto-di-nuovo-motore-per-pompe-idrauliche\/#primaryimage"},"image":{"@id":"https:\/\/came-italy.com\/it\/la-collaborazione-tra-came-e-cliente-per-il-progetto-di-nuovo-motore-per-pompe-idrauliche\/#primaryimage"},"thumbnailUrl":"https:\/\/came-italy.com\/wp-content\/uploads\/2022\/05\/La-collaborazione-tra-Came-e-cliente.jpg","datePublished":"2022-05-05T09:29:04+00:00","breadcrumb":{"@id":"https:\/\/came-italy.com\/it\/la-collaborazione-tra-came-e-cliente-per-il-progetto-di-nuovo-motore-per-pompe-idrauliche\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/came-italy.com\/it\/la-collaborazione-tra-came-e-cliente-per-il-progetto-di-nuovo-motore-per-pompe-idrauliche\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/came-italy.com\/it\/la-collaborazione-tra-came-e-cliente-per-il-progetto-di-nuovo-motore-per-pompe-idrauliche\/#primaryimage","url":"https:\/\/came-italy.com\/wp-content\/uploads\/2022\/05\/La-collaborazione-tra-Came-e-cliente.jpg","contentUrl":"https:\/\/came-italy.com\/wp-content\/uploads\/2022\/05\/La-collaborazione-tra-Came-e-cliente.jpg","width":850,"height":450},{"@type":"BreadcrumbList","@id":"https:\/\/came-italy.com\/it\/la-collaborazione-tra-came-e-cliente-per-il-progetto-di-nuovo-motore-per-pompe-idrauliche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/came-italy.com\/it\/"},{"@type":"ListItem","position":2,"name":"La collaborazione tra Came e cliente per il progetto di nuovo motore per pompe idrauliche"}]},{"@type":"WebSite","@id":"https:\/\/came-italy.com\/it\/#website","url":"https:\/\/came-italy.com\/it\/","name":"Came Spa","description":"Avvolgimenti e componenti per motori elettrici","publisher":{"@id":"https:\/\/came-italy.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/came-italy.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/came-italy.com\/it\/#organization","name":"Came Spa","url":"https:\/\/came-italy.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/came-italy.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/came-italy.com\/wp-content\/uploads\/2016\/07\/logo-came-spa.png","contentUrl":"https:\/\/came-italy.com\/wp-content\/uploads\/2016\/07\/logo-came-spa.png","width":766,"height":129,"caption":"Came Spa"},"image":{"@id":"https:\/\/came-italy.com\/it\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/came-italy.com\/it\/#\/schema\/person\/da677687caf9ad54b55d15c77d264d7c","name":"Andrea Toniolo","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/e1912c0d135981b2b041c8e10cbcfb1463c1fd2a779fcae4dd31d8add9c64804?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e1912c0d135981b2b041c8e10cbcfb1463c1fd2a779fcae4dd31d8add9c64804?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e1912c0d135981b2b041c8e10cbcfb1463c1fd2a779fcae4dd31d8add9c64804?s=96&d=mm&r=g","caption":"Andrea Toniolo"},"url":"https:\/\/came-italy.com\/it\/author\/andrea\/"}]}},"_links":{"self":[{"href":"https:\/\/came-italy.com\/it\/wp-json\/wp\/v2\/posts\/13528","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/came-italy.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/came-italy.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/came-italy.com\/it\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/came-italy.com\/it\/wp-json\/wp\/v2\/comments?post=13528"}],"version-history":[{"count":12,"href":"https:\/\/came-italy.com\/it\/wp-json\/wp\/v2\/posts\/13528\/revisions"}],"predecessor-version":[{"id":13670,"href":"https:\/\/came-italy.com\/it\/wp-json\/wp\/v2\/posts\/13528\/revisions\/13670"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/came-italy.com\/it\/wp-json\/wp\/v2\/media\/13666"}],"wp:attachment":[{"href":"https:\/\/came-italy.com\/it\/wp-json\/wp\/v2\/media?parent=13528"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/came-italy.com\/it\/wp-json\/wp\/v2\/categories?post=13528"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/came-italy.com\/it\/wp-json\/wp\/v2\/tags?post=13528"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}